{"id":787,"date":"2013-02-02T13:50:22","date_gmt":"2013-02-02T18:50:22","guid":{"rendered":"https:\/\/se.csbe.qc.ca\/etienne\/?p=787"},"modified":"2019-11-24T20:49:37","modified_gmt":"2019-11-25T01:49:37","slug":"clair-2013-tous-invites-a-voir-leducation-autrement","status":"publish","type":"post","link":"https:\/\/se.csbe.qc.ca\/etienne\/2013\/02\/02\/clair-2013-tous-invites-a-voir-leducation-autrement\/","title":{"rendered":"Clair 2013 : Tous invit\u00e9s \u00e0 voir l\u2019\u00e9ducation autrement!"},"content":{"rendered":"<div class=\"page-restrict-output\"><p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"\" src=\"http:\/\/clair2013.wikispaces.com\/file\/view\/LogoClair2013.jpeg\/364757782\/LogoClair2013.jpeg\" width=\"269\" height=\"115\" \/>Et si on faisait un\u00a0<a href=\"http:\/\/clair2013.wikispaces.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00e9v\u00e8nement\u00a0<\/a>semblable en Beauce en beauce&#8230;<\/p>\n<p>L&rsquo;infobourg en\u00a0parle\u00a0<a href=\"http:\/\/www.infobourg.com\/2013\/01\/30\/clair-2013-tous-invites-a-voir-leducation-autrement\/?utm_source=twitterfeed&amp;utm_medium=facebook&amp;utm_campaign=Infobourg\" target=\"_blank\" rel=\"noopener noreferrer\">ici<\/a>.<\/p>\n<blockquote><p><strong>Clair, petit village du nord-ouest du Nouveau-Brunswick, s\u2019animera d\u2019une passion \u00e9ducative hors du commun d\u00e8s demain et jusqu\u2019au 2 f\u00e9vrier. Enseignants et professionnels de l\u2019\u00e9ducation de partout s\u2019y retrouveront le temps d\u2019un colloque visant \u00e0 am\u00e9liorer leur connaissance du Web 2.0 et voir l\u2019\u00e9ducation autrement.<\/strong><\/p><\/blockquote>\n<\/div><div class=\"al2fb_like_button\"><div id=\"fb-root\"><\/div><script type=\"text\/javascript\">\n(function(d, s, id) {\n  var js, fjs = d.getElementsByTagName(s)[0];\n  if (d.getElementById(id)) return;\n  js = d.createElement(s); js.id = id;\n  js.src = \"\/\/connect.facebook.net\/fr_FR\/all.js#xfbml=1&appId=148229171995028\";\n  fjs.parentNode.insertBefore(js, fjs);\n}(document, \"script\", \"facebook-jssdk\"));\n<\/script>\n<fb:like href=\"https:\/\/se.csbe.qc.ca\/etienne\/2013\/02\/02\/clair-2013-tous-invites-a-voir-leducation-autrement\/\" layout=\"button_count\" show_faces=\"true\" share=\"false\" width=\"450\" action=\"like\" font=\"tahoma\" colorscheme=\"light\" ref=\"AL2FB\"><\/fb:like><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"page-restrict-output\"><p>Et si on faisait un\u00a0\u00e9v\u00e8nement\u00a0semblable en Beauce en beauce&#8230; L&rsquo;infobourg en\u00a0parle\u00a0ici. Clair, petit village du nord-ouest du Nouveau-Brunswick, s\u2019animera d\u2019une passion \u00e9ducative hors du commun d\u00e8s demain et jusqu\u2019au 2 f\u00e9vrier. Enseignants et professionnels de l\u2019\u00e9ducation de partout s\u2019y retrouveront le temps d\u2019un colloque visant \u00e0 am\u00e9liorer leur connaissance du Web 2.0 et voir l\u2019\u00e9ducation &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/se.csbe.qc.ca\/etienne\/2013\/02\/02\/clair-2013-tous-invites-a-voir-leducation-autrement\/\">Lire la suite<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[139,138,249],"coauthors":[],"class_list":["post-787","post","type-post","status-publish","format-standard","hentry","category-brbev","tag-education","tag-evenement","tag-technologie","item-wrap"],"_links":{"self":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts\/787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/comments?post=787"}],"version-history":[{"count":4,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts\/787\/revisions"}],"predecessor-version":[{"id":2809,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts\/787\/revisions\/2809"}],"wp:attachment":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/media?parent=787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/categories?post=787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/tags?post=787"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/coauthors?post=787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}