{"id":775,"date":"2013-02-02T13:14:49","date_gmt":"2013-02-02T18:14:49","guid":{"rendered":"https:\/\/se.csbe.qc.ca\/etienne\/?p=775"},"modified":"2019-11-24T20:49:41","modified_gmt":"2019-11-25T01:49:41","slug":"connaitre-les-origines-de-linternet-et-du-web","status":"publish","type":"post","link":"https:\/\/se.csbe.qc.ca\/etienne\/2013\/02\/02\/connaitre-les-origines-de-linternet-et-du-web\/","title":{"rendered":"Conna\u00eetre les origines de l&rsquo;Internet et du Web"},"content":{"rendered":"<div class=\"page-restrict-output\"><p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"\" src=\"http:\/\/cursus.edu\/media\/image\/18990_reseau.png\" width=\"136\" height=\"136\" \/>Toujours <a href=\"http:\/\/cursus.edu\/dossiers-articles\/articles\/18990\/connaitre-les-origines-internet-web\/\" target=\"_blank\" rel=\"noopener noreferrer\">THOT<\/a>&#8230;<\/p>\n<blockquote><p>L&rsquo;histoire de l&rsquo;Internet se confond bien souvent avec celle du Web dans les discours, les deux termes \u00e9tant souvent utilis\u00e9s de mani\u00e8re indiff\u00e9rente par bon nombre de personnes. Un\u00a0<a title=\"S\u2019ouvre dans une nouvelle fen\u00eatre.\" href=\"http:\/\/www.franceculture.fr\/emission-place-de-la-toile-au-fait-qui-a-invente-internet-2012-10-27\" target=\"_blank\" rel=\"noopener noreferrer\">r\u00e9cent num\u00e9ro<\/a>radiophonique de\u00a0<strong>Place de la Toile<\/strong>\u00a0sur la cha\u00eene fran\u00e7aise France Culture revient sur cette question de la cr\u00e9ation d&rsquo;Internet, notamment \u00e0 l&rsquo;occasion d&rsquo;une\u00a0<a title=\"S\u2019ouvre dans une nouvelle fen\u00eatre.\" href=\"http:\/\/online.wsj.com\/article\/SB10000872396390444464304577539063008406518.html#articleTabs%3Dcomments\" target=\"_blank\" rel=\"noopener noreferrer\">tribune<\/a>pol\u00e9mique\u00a0<em>\u00ab\u00a0truff\u00e9e d&rsquo;erreurs factuelles sur l&rsquo;histoire des r\u00e9seaux\u00a0\u00bb<\/em>\u00a0publi\u00e9e par Gordon Crovitz sur le site du Wall Street Journal&#8230;<\/p><\/blockquote>\n<\/div><div class=\"al2fb_like_button\"><div id=\"fb-root\"><\/div><script type=\"text\/javascript\">\n(function(d, s, id) {\n  var js, fjs = d.getElementsByTagName(s)[0];\n  if (d.getElementById(id)) return;\n  js = d.createElement(s); js.id = id;\n  js.src = \"\/\/connect.facebook.net\/fr_FR\/all.js#xfbml=1&appId=148229171995028\";\n  fjs.parentNode.insertBefore(js, fjs);\n}(document, \"script\", \"facebook-jssdk\"));\n<\/script>\n<fb:like href=\"https:\/\/se.csbe.qc.ca\/etienne\/2013\/02\/02\/connaitre-les-origines-de-linternet-et-du-web\/\" layout=\"button_count\" show_faces=\"true\" share=\"false\" width=\"450\" action=\"like\" font=\"tahoma\" colorscheme=\"light\" ref=\"AL2FB\"><\/fb:like><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"page-restrict-output\"><p>Toujours THOT&#8230; L&rsquo;histoire de l&rsquo;Internet se confond bien souvent avec celle du Web dans les discours, les deux termes \u00e9tant souvent utilis\u00e9s de mani\u00e8re indiff\u00e9rente par bon nombre de personnes. Un\u00a0r\u00e9cent num\u00e9roradiophonique de\u00a0Place de la Toile\u00a0sur la cha\u00eene fran\u00e7aise France Culture revient sur cette question de la cr\u00e9ation d&rsquo;Internet, notamment \u00e0 l&rsquo;occasion d&rsquo;une\u00a0tribunepol\u00e9mique\u00a0\u00ab\u00a0truff\u00e9e d&rsquo;erreurs factuelles &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/se.csbe.qc.ca\/etienne\/2013\/02\/02\/connaitre-les-origines-de-linternet-et-du-web\/\">Lire la suite<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[137,136],"coauthors":[],"class_list":["post-775","post","type-post","status-publish","format-standard","hentry","category-brbev","tag-histoire","tag-internet","item-wrap"],"_links":{"self":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts\/775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/comments?post=775"}],"version-history":[{"count":4,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts\/775\/revisions"}],"predecessor-version":[{"id":2812,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts\/775\/revisions\/2812"}],"wp:attachment":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/media?parent=775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/categories?post=775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/tags?post=775"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/coauthors?post=775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}