{"id":410,"date":"2012-12-12T22:08:05","date_gmt":"2012-12-12T21:08:05","guid":{"rendered":"https:\/\/se.csbe.qc.ca\/etienne\/?p=410"},"modified":"2019-11-24T20:23:40","modified_gmt":"2019-11-25T01:23:40","slug":"parole-des-jeunes-et-domaines-scientifiques-de-lavenir","status":"publish","type":"post","link":"https:\/\/se.csbe.qc.ca\/etienne\/2012\/12\/12\/parole-des-jeunes-et-domaines-scientifiques-de-lavenir\/","title":{"rendered":"Parole des jeunes et domaines scientifiques de l\u2019avenir"},"content":{"rendered":"<div class=\"page-restrict-output\"><p><a href=\"http:\/\/liledusavoir.wordpress.com\/atelier-3-paroles-des-jeunes\/\" target=\"_blank\" rel=\"noopener noreferrer\">Je relais&#8230;<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/3x-zmS7BoiE?feature=player_embedded\" frameborder=\"0\" width=\"320\" height=\"180\"><\/iframe><\/p>\n<\/div><div class=\"al2fb_like_button\"><div id=\"fb-root\"><\/div><script type=\"text\/javascript\">\n(function(d, s, id) {\n  var js, fjs = d.getElementsByTagName(s)[0];\n  if (d.getElementById(id)) return;\n  js = d.createElement(s); js.id = id;\n  js.src = \"\/\/connect.facebook.net\/fr_FR\/all.js#xfbml=1&appId=148229171995028\";\n  fjs.parentNode.insertBefore(js, fjs);\n}(document, \"script\", \"facebook-jssdk\"));\n<\/script>\n<fb:like href=\"https:\/\/se.csbe.qc.ca\/etienne\/2012\/12\/12\/parole-des-jeunes-et-domaines-scientifiques-de-lavenir\/\" layout=\"button_count\" show_faces=\"true\" share=\"false\" width=\"450\" action=\"like\" font=\"tahoma\" colorscheme=\"light\" ref=\"AL2FB\"><\/fb:like><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"page-restrict-output\"><p>Je relais&#8230; &nbsp;<\/p>\n<\/div>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,11,12],"tags":[],"coauthors":[],"class_list":["post-410","post","type-post","status-publish","format-standard","hentry","category-idees-a-partager","category-japprends","category-je-reflechis","item-wrap"],"_links":{"self":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts\/410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/comments?post=410"}],"version-history":[{"count":3,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts\/410\/revisions"}],"predecessor-version":[{"id":2754,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/posts\/410\/revisions\/2754"}],"wp:attachment":[{"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/media?parent=410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/categories?post=410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/tags?post=410"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/etienne\/wp-json\/wp\/v2\/coauthors?post=410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}