{"id":592,"date":"2015-02-02T14:10:13","date_gmt":"2015-02-02T16:10:13","guid":{"rendered":"https:\/\/se.csbe.qc.ca\/biblio\/?p=592"},"modified":"2015-02-05T11:30:29","modified_gmt":"2015-02-05T13:30:29","slug":"point-dexclamation-un-album-coup-de-coeur","status":"publish","type":"post","link":"https:\/\/se.csbe.qc.ca\/biblio\/2015\/02\/02\/point-dexclamation-un-album-coup-de-coeur\/","title":{"rendered":"Point d&rsquo;exclamation : un album coup de coeur"},"content":{"rendered":"<div class=\"page-restrict-output\"><p>Voici un adorable album qui permet de mettre en valeur l\u2019int\u00e9r\u00eat de la ponctuation. Gr\u00e2ce \u00e0 sa rencontre avec le point d\u2019interrogation, Point d\u2019exclamation apprend \u00e0 s&rsquo;accepter et \u00e0 c\u00e9l\u00e9brer sa diff\u00e9rence.<\/p>\n<p>Consulter les pistes d\u2019exploration sur le site de <a title=\"Point d'exclamation\" href=\"http:\/\/www.livresouverts.qc.ca\/index.php?p=il&amp;lo=47600\" target=\"_blank\">Livres ouverts<\/a><\/p>\n<p>Conseill\u00e9 pour les \u00e9l\u00e8ves de 1re, 2e et 3e ann\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Point d&rsquo;exclamation<\/strong><\/em><\/p>\n<p>Amy Krouse Rosenthal<\/p>\n<p>Scholastic, 2013<\/p>\n<p>ISNB\u00a0: 9781443129381<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-593 \" src=\"https:\/\/se.csbe.qc.ca\/biblio\/files\/2015\/01\/Point.jpg\" alt=\"Point\" width=\"195\" height=\"131\" srcset=\"https:\/\/se.csbe.qc.ca\/biblio\/files\/2015\/01\/Point.jpg 817w, https:\/\/se.csbe.qc.ca\/biblio\/files\/2015\/01\/Point-300x202.jpg 300w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"page-restrict-output\"><p>Voici un adorable album qui permet de mettre en valeur l\u2019int\u00e9r\u00eat de la ponctuation. Gr\u00e2ce \u00e0 sa rencontre avec le point d\u2019interrogation, Point d\u2019exclamation apprend \u00e0 s&rsquo;accepter et \u00e0 c\u00e9l\u00e9brer sa diff\u00e9rence. Consulter les pistes d\u2019exploration sur le site de Livres ouverts Conseill\u00e9 pour les \u00e9l\u00e8ves de 1re, 2e et 3e ann\u00e9e. &nbsp; Point d&rsquo;exclamation [&hellip;]<\/p>\n<\/div>","protected":false},"author":426,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[65,66,74,119,125],"class_list":["post-592","post","type-post","status-publish","format-standard","hentry","category-capsules-litteraires","tag-1er-cycle","tag-2e-cycle","tag-album","tag-ponctuation","tag-primaire"],"_links":{"self":[{"href":"https:\/\/se.csbe.qc.ca\/biblio\/wp-json\/wp\/v2\/posts\/592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/se.csbe.qc.ca\/biblio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/se.csbe.qc.ca\/biblio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/biblio\/wp-json\/wp\/v2\/users\/426"}],"replies":[{"embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/biblio\/wp-json\/wp\/v2\/comments?post=592"}],"version-history":[{"count":2,"href":"https:\/\/se.csbe.qc.ca\/biblio\/wp-json\/wp\/v2\/posts\/592\/revisions"}],"predecessor-version":[{"id":611,"href":"https:\/\/se.csbe.qc.ca\/biblio\/wp-json\/wp\/v2\/posts\/592\/revisions\/611"}],"wp:attachment":[{"href":"https:\/\/se.csbe.qc.ca\/biblio\/wp-json\/wp\/v2\/media?parent=592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/biblio\/wp-json\/wp\/v2\/categories?post=592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/se.csbe.qc.ca\/biblio\/wp-json\/wp\/v2\/tags?post=592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}